{"id":2509,"date":"2014-01-09T11:43:46","date_gmt":"2014-01-09T10:43:46","guid":{"rendered":"https:\/\/www.epidemicrecords.net\/?p=2509"},"modified":"2014-01-09T11:43:46","modified_gmt":"2014-01-09T10:43:46","slug":"kalashnikov-collective-piu-che-una-band-intervista-italian-only","status":"publish","type":"post","link":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/","title":{"rendered":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band &#8211; intervista &#8211; [italian only]"},"content":{"rendered":"<p>I Kalashnikov (o meglio, <strong>Kalashnikov Collective<\/strong>) sono pi\u00f9 che una band e negli anni l&#8217;hanno saputo dimostrare al meglio. <strong>Una realt\u00e0 creativa, vivace e al di fuori di molti schemi<\/strong>. Intervistarli \u00e8 stato un piacere: leggere risposte cos\u00ec sincere e che hanno il sapore di una coscienza conquistata e forgiata negli anni mi ha fatto apprezzare ancora di pi\u00f9 la genuinit\u00e0 di questa band&#8230; che \u00e8 pi\u00f9 che una band!<br \/>\n<strong>I loro discorsi valgono per tutti, dai punk pi\u00f9 trasandati ai kids pi\u00f9 modaioli<\/strong>: tutti dovrebbero fermarsi, leggere e riflettere. Perch\u00e8 da alcune persone c&#8217;\u00e8 proprio tanto da imparare, che si possa condividere o meno la visione che propongono.<\/p>\n<p>Poche chiacchiere. Ecco a voi una bella intervista: Kalashnikov Collective, romantic punx da Milano!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/1236617_10151680155897717_368358450_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2513\" alt=\"\" src=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/1236617_10151680155897717_368358450_n1-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/1236617_10151680155897717_368358450_n1-300x225.jpg 300w, https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/1236617_10151680155897717_368358450_n1.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\"><b>1) Kalashnikov Collective: un collettivo quindi, non una band. E&#8217; una provocazione oppure c&#8217;\u00e8 del vero in questo? Cosa c&#8217;\u00e8 di diverso nel rapporto tra i vari membri del gruppo? E verso la musica in generale?<\/b><\/p>\n<p align=\"JUSTIFY\">Collettivo significa \u201cpersone che stanno insieme per un fine comune\u201d. Il termine band, o gruppo, invece indica \u201cpersone che stanno insieme per suonare\u201d, ciascuna identificata nel suo strumento o nel suo ruolo predefinito. Troviamo che la parola collettivo sia pi\u00f9 libera e, perci\u00f2, maggiormente adatta a descrivere quello che facciamo, dove sono importanti le idee, non tanto l&#8217;affermazione narcisistica della persona. Nessuno di noi si identifica particolarmente con lo strumento che suona, come farebbe un qualsiasi \u201cprofessionista\u201d: piuttosto ciascuno aiuta gli altri portando avanti un pezzo del progetto Kalashnikov, che utilizza la musica, scrittura, immagini e il nostro stesso modo di essere per veicolare idee libertarie. Nessuna facile provocazione, quindi! Infine ci sembrava giusto per ripensare anche ci\u00f2 che si da per scontato, come il fatto che se suoni assieme ad altre persone devi per forza definirti come una \u201cband\u201d. Questo termine ricorda il \u201cdivismo\u201d, l&#8217;idolatria nei confronti del musicista promossa dal music-business ufficiale, con relativo codazzo di \u201cfans\u201d consumatori da ammansire affinch\u00e9 continuino ad acquistare. Tutto questo non ci appartiene, per cui&#8230;ebbene s\u00ec, siamo un collettivo!<\/p>\n<p align=\"JUSTIFY\"><b>2) Suonate una musica molto personale, una ricetta tutta vostra che potrebbe essere quasi identificata come visionaria. Da dove deriva questa ecletticit\u00e0? E&#8217; tutta farina del vostro sacco oppure anche voi come tutti avete delle band di riferimento?<\/b><\/p>\n<p align=\"JUSTIFY\">Quando abbiamo iniziato con i Kalashnikov (alcuni secoli fa) eravamo volevamo semplicemente suonare la musica che ci sarebbe piaciuto ascoltare. Pu\u00f2 sembrare un po\u2019 pretenzioso, ma alla fine \u00e8 cos\u00ec. Siamo cresciuti ascoltando punk: il nostro immaginario, la nostra etica, la nostra ispirazione \u00e8 sempre stata legata a quel mondo; per\u00f2 non ci siamo mai identificati in quell\u2019immagine machista e ginnica dell\u2019h.c. che andava di moda negli anni \u201990 (anni nei quali siamo cresciuti), quell\u2019intransigenza sonora, quell\u2019essere per forza \u201ca muso duro\u201d, il fatto di dover suonare a tutti i costi veloci, rumorosi, cinici\u2026 n\u00e9 ci piaceva l\u2019attitudine cazzonara di tante band punk-rock dell\u2019epoca. Tutti, bene o male, avevano come riferimento gli Stati uniti, quella sottocultura da cui venivano fuori i Green day, i Nofx e tutti i gruppi pi\u00f9 o meno \u201cdivertenti\u201d degli anni \u201990. Noi invece amavamo i Wretched, i Discharge, gli Anti-cimex, gli Aus Rotten, i Nausea, il crust giapponese, tutto il vecchio anarco-punk inglese del giro Crass\u2026 quell\u2019immaginario, quella urgenza, quel modo di intendere il punk, molto politico e con radici profondamente e fieramente DIY\u2026 Per\u00f2 amavamo anche musicisti che non avevano a che fare con il punk e che avevano scritto belle canzoni con testi poetici, che potevano essere inni contro il sistema, contro un certo modo di vivere e affrontare il mondo, che raccontavano storie in grado di emozionare, far piangere, far gioire\u2026 Con i Kalashnikov volevamo trovare una specie di via in mezzo a tutto questo: essere punk (non potevamo essere nient\u2019altro, direi!), ma in un modo nostro che unisse la poesia e la politica, l\u2019amore e l\u2019anarchia, il significato e la musica, in maniera organica, senza dover per forza essere o incazzati o melensi. Un po\u2019 come quello che hanno fatto alcuni gruppi punk originali, che hanno cercato di andare aldil\u00e0 degli schemi punk\/hc (mi vengono in mente i Chumbawamba, ma anche altri gruppi inglesi di cui si conosce poco del periodo successivo agli esordi punk, come Anti-Nowhere League, Blitz, Chron Gen, Uk Subs, Angelic Upstarts \u2026 che negli anni \u201980 inoltrati incisero dischi davvero belli e strani, che non suonavano pi\u00f9 classicamente punk rock), oppure musicisti come Robert Wyatt, Peter Gabriel (in Inghilterra), il Banco del Mutuo Soccorso, gli Area (in Italia), che tra gli anni settanta e gli ottanta non hanno mai rinunciato a scrivere musica \u201cpolitica\u201d e creativa pur nel contesto del music businnes e secondo le formule pop, seguendo una strada tracciata da loro e da nessun altro.<\/p>\n<p align=\"JUSTIFY\">Da tutto questo \u00e8 nata quella definizione un po\u2019 contraddittoria e provocatoria di \u201cromantic punk\u201d. Non c\u2019\u00e8 niente di apparentemente romantico nel punk, ma siamo tutti umani, viviamo tutti di passioni, emozioni, sentimenti pi\u00f9 complessi dell\u2019odio e della rabbia\u2026 quindi perch\u00e9 negarlo? Nella nostra prima cassetta si leggeva: \u201cPerch\u00e9 essere punk se puoi essere te stesso?\u201d, una frase che colp\u00ec molto chi la leggeva, anche se oggi non la userei pi\u00f9, perch\u00e9 mi sembra un po\u2019 trita e facile da fraintendere\u2026 il suo significato era semplicemente: basta omologarsi ai soliti modelli! Anche se si tratta di modelli \u201calternativi\u201d, come il punk, che tra l\u2019altro, in quegli anni (fine \u201890), era diventato un genere musicale di massa e non rappresentava pi\u00f9 un bel niente di realmente alternativo. Autodeterminazione!<\/p>\n<p align=\"JUSTIFY\">A livello strettamente musicale, ci siamo sempre sentiti liberi di fare quello che ci piaceva, senza pensare al fatto che una cosa o l\u2019altra non fosse adatta per il \u201cgenere\u201d. L\u2019importante era scrivere belle canzoni e realizzare le idee che avevamo in testa, aldil\u00e0 del riff, degli arrangiamenti o delle scelte di suono. Fin dall\u2019inizio dei Kalashnikov ascoltavamo generi musicali che non c\u2019entravano nulla col punk, dal rock psichedelico degli anni \u201860 (Doors in particolare) al rock progressivo di gruppi come King Crimson, Camel, Genesis, dall\u2019ambient dei musicisti kraut-rock come Popol Vuh, Tangerine Dream e Klaus Schulze alla musica etnica e tradizionale, in particolare quella russa, che all\u2019inizio dei Kalashnikov ci influenz\u00f2 molto. Il nome \u201cKalashnikov\u201d \u00e8 nato proprio per dire: la nostra ispirazione non arriva da ovest (gli USA), ma da est! Una specie di scelta di campo da tempi della Guerra Fredda! C\u2019\u00e8 stato un periodo in cui ascoltavamo tantissima musica tradizionale russa, eravamo andati anche ad un terribile concerto del corpo di canto dell\u2019Armata Rossa\u2026 il pubblico era composto da settantenni, ma ci divertimmo un sacco, era bellissimo sentire quelle melodie, quei brani che conoscevamo a memoria suonati dal vivo, anche se si trattava di qualcosa di molto simile ad un\u2019orchestra di liscio\u2026 Questo per farti capire che musicalmente siamo sempre stati molto eclettici e non ci siamo mai preoccupati che una cosa appartenesse ad un genere piuttosto che ad un altro. L\u2019etica punk ci ha insegnato che spesso le cose importanti stanno dietro all\u2019apparenza \u201cmusicale\u201d, ovvero nell\u2019attitudine, nell\u2019approccio, nel significato, in quello che trasmetti e comunichi.<\/p>\n<p align=\"JUSTIFY\"><b>3) Siete un gruppo composto da persone che prestano molta attenzione alla politica. Come vedete l&#8217;etichetta, spesso abusata, di &#8220;gruppo politico&#8221; che viene data a band punk e hardcore? Pensate che sia riduttivo, limitante e vincolante oppure c&#8217;\u00e8 del buono in questa definizione?<\/b><\/p>\n<p align=\"JUSTIFY\">C\u2019\u00e8 un certo fraintendimento sulla parola \u201cpolitica\u201d e sul concetto di \u201cband politica\u201d\u2026 Noi la vediamo in questi termini: ci sono gruppi che fanno veri e propri proclami politici, altri invece che &#8211; come noi \u00a0&#8211; parlano di altre cose nelle proprie canzoni per\u00f2 poi risultano ugualmente un gruppo \u201cpolitico\u201d. Perch\u00e9? Perch\u00e9 la politica, al nostro livello, \u00e8 una questione di scelte di vita, di etica, di rapporti umani, di tensioni, non di tessere, ideologie, di proclami\u2026 La politica nella sua accezione parolaia e sloganistica non ci piace: quello che ci interessa \u00e8 la vita, nella quale le scelte \u201cpolitiche\u201d vengono messe in pratica, dove diventano azione, rapporti sociali, quotidianit\u00e0. Ognuno di noi, nel collettivo, ha le proprie convinzioni politiche ed etiche, partecipa al movimento in maniera differente, mentre con il gruppo quello che ci interessa fare di \u201cpolitico\u201d \u00e8 portare avanti l\u2019idea di un certo modo di fare le cose, di vivere in mezzo alla gente. Non vogliamo essere un gruppo anarchico, autonomo, eco radicale, vegano\u2026 cio\u00e8 legato a determinato \u201cbandiere\u201d\u2026\u00a0 non vogliamo essere catalogati sotto un\u2019etichetta ideologica; quelle cose (vegano, anarchico etcetc\u2026) ciascuno di noi sceglie di esserle nella vita e di comportarsi di conseguenza, e tutti noi cerchiamo di portare le nostre scelte tra le persone che frequentiamo, nei posti dove andiamo. Siamo percepiti come gruppo politico perch\u00e9 noi siamo persone che danno importanza a certi valori, a certe idee, e tutti lo sanno, lo capiscono da quello che facciamo e da come lo facciamo. Che poi cantiamo storie d\u2019amore o di \u201cfottere il sistema\u201d, poco importa. Il punk non \u00e8 nato dai proclami politici: \u00e8 nato come prassi rivoluzionaria, almeno per quanto riguarda l\u2019organizzazione sociale, le gerarchie, l\u2019arte, il mercato. E\u2019 stato un movimento nato anche dal disgusto delle nuove generazioni per la politica fatta nelle sedi di partito, nei libri e nei comizi, e che ha proposto\/rivalutato una \u201cvia politica\u201d al fare (musica, concerti, ma anche altro) che bastasse a se stessa, un modo di vivere con le persone e il mondo che ti circonda, un sistema alternativo di valori estetici, un modo pratico per rifiutare le regole del mercato capitalista e della societ\u00e0 dei consumi\u2026 Questa \u00e8 la base. Poi vengono i testi politici, poi vengono le prese di posizione, le rivendicazioni di appartenenza, gli slogan etcetc\u2026 ma prima di tutto il punk \u00e8 un modo di fare e di vivere con gli altri nel quotidiano, che si rispecchia nella gestione del tuo gruppo e della tua musica. Senza questo aspetto non c\u2019\u00e8 il punk, c\u2019\u00e8 solo un genere musicale come tanti altri.<\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><a href=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/11209_10151680155907717_549086134_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2514\" alt=\"\" src=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/11209_10151680155907717_549086134_n1-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/11209_10151680155907717_549086134_n1-300x225.jpg 300w, https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/11209_10151680155907717_549086134_n1.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\"><b>4) Recentemente avete pubblicato un ironico (ma comunque realistico) manualetto di istruzioni per chi volesse invitarvi a suonare (doverosa la lettura: <\/b><span style=\"color: #000080;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.facebook.com\/permalink.php?story_fbid=10151706763877717&amp;id=76292207716\">https:\/\/www.facebook.com\/permalink.php?story_fbid=10151706763877717&amp;id=76292207716<\/a><\/span><\/span><b> ). Era ora che qualcuno dicesse certe cose, che possono sembrare ovvie a chi usa un minimo di criterio nel far le cose, ma che per molti ancora suona come assurdo. Che risposta ha avuto questo breve testo? Pensate che ci sia il modo di cambiare le cose per quanto riguarda l&#8217;organizzazione di eventi che richiedono l&#8217;apporto musicale\/artistico di band per cause legate all&#8217;attivismo politico?<\/b><\/p>\n<p align=\"JUSTIFY\">Noi siamo molto conosciuti nel giro per la nostra disponibilit\u00e0 a supportare gli spazi occupati e a sostenere i benefit per i compagni e le compagne che si trovano in difficolt\u00e0;\u00a0 cosa che facciamo sempre con spirito di solidariet\u00e0 e complicit\u00e0; il che tradotto, significa che non chiediamo mai un tot di soldi n\u00e9 abbiamo particolari pretese quando andiamo in giro a suonare. In oltre dieci anni di attivit\u00e0 di situazioni scassate ne abbiamo vissute parecchie, ma questo non ci ha fatto certo cambiare idea sulle scelte etiche che abbiamo fatto e facciamo tutt\u2019ora.<\/p>\n<p align=\"JUSTIFY\">Ci piace per\u00f2 anche essere onesti con noi e con gli altri, e siamo anche persone spiritose che amano farsi due risate, anche di fronte alla pi\u00f9 disagevole delle situazioni e alla disorganizzazione pi\u00f9 clamorosa. Diciamo che siamo abbastanza di bocca buona: abbiamo dormito in furgone in pieno inverno, sul palco dopo il concerto, in un fienile invaso dai topi, in posti senz\u2019acqua e senza elettricit\u00e0, in case pericolanti, in mezzo alla merda di cane, in letti invasi dalle formiche, con il sole in faccia, la musica a palla per tutta la notte, con la gente che scopava sul materasso di fianco, in un orto abusivo, in posti in cui non ci stavamo nemmeno sdraiati, in sette in un camper, in una tenda in mezzo al bosco con due gradi sottozero, mangiato riso da un catino, bevuto acqua piovana, tornati a casa alle cinque del mattino in mezzo a bufere di neve, banchi di nebbia impenetrabili, dopo centinaia di chilometri di veglia\u2026 insomma, hai capito.<\/p>\n<p align=\"JUSTIFY\">Per\u00f2 \u00e8 anche vero che per evitare situazioni disagevoli e garantire ai gruppi un minimo di confort basterebbe un piccolo sforzo d\u2019attenzione in pi\u00f9. Niente di che. E\u2019 questo che volevamo dire con quella specie di vademecum.<\/p>\n<p align=\"JUSTIFY\">Per quanto riguarda nello specifico i benefit, sintetizzerei tutto dicendo che a volte i benefit si trasformano in malefit, per i gruppi che ci suonano (che non prendono un centesimo per il rimborso), per gli organizzatori (che ci smenano pure loro dei soldi). Ovvero: spesso sarebbe meglio che i gruppi (anzich\u00e9 prendere il furgone, regalare soldi alla societ\u00e0 autostrade, agli autogrill, ai benzinai, sparandosi un mare di chilometri) facessero una bella e sana colletta tra loro, spedendo i soldi da casa direttamente al destinatario del benefit. Suonare benefit davanti a dieci persone e tirar su 30 euro da devolvere alla causa \u00e8 simpatico, e tutto sommato ci fa sempre piacere, ma a volte qualche domanda te la fai. E\u2019 un discorso molto razionale, e per questo un po\u2019 grigio, lo so, per\u00f2 se \u00e8 la causa ad essere importante, allora \u00e8 giusto che le energie vengano convogliate in essa, e non che la causa diventi un mero pretesto per organizzare un concerto a costo zero.<\/p>\n<p align=\"JUSTIFY\">In fondo, ci\u00f2 che bisogna fare per migliorare, come dici, \u201cl&#8217;organizzazione di eventi\u201d sta proprio nella tua frase: ovvero nell\u2019organizzazione! E\u2019 banale, ma \u00e8 il primo (e forse anche l\u2019ultimo?) passo: sbattersi, organizzare al meglio e curare ogni aspetto con la medesima passione, con senso di realt\u00e0 e senso pratico! Almeno questo. Poi le cose possono sempre andar male comunque, ma almeno quello che \u00e8 in tuo potere l\u2019avrai fatto!<\/p>\n<p align=\"JUSTIFY\">La risposta che ha avuto il nostro post? Beh, grandissima solidariet\u00e0 da parte dei \u201cmusicisti\u201d come noi\u2026 e nessun riscontro da parte del resto del mondo!<\/p>\n<p align=\"JUSTIFY\"><b>5) Se non sbaglio portate avanti anche una distro. Cosa distribuite? E sempre se non sbaglio, mi sembra di aver capito che la distro funziona ad offerta libera. Qual&#8217;\u00e8 la risposta del pubblico a questo tipo di iniziativa?<\/b><\/p>\n<p align=\"JUSTIFY\">S\u00ec, abbiamo una distro di materiali (dischi, libri, &#8216;zines, magliette e toppe&#8230;) legati al circuito DIY o anarchico-libertario. Cercando una coerenza con questo tipo di idee, abbiamo pensato di rifiutare la logica della \u201cvendita\u201d, dove i ruoli e le gerarchie sono rigidamente definite, per rifarci a qualcosa di pi\u00f9 simile al \u201cbaratto\u201d. Cos\u00ec \u00e8 nata questa idea del \u201cprezzo libero\u201d che, dobbiamo dire, \u00e8 stata davvero azzeccata perch\u00e9 spiazza e spinge a porsi delle domande. Quando qualcuno si avvicina al banchetto e ci chiede \u201cQuanto costa?\u201d, si sente rispondere: \u201cQuello che pensi che valga\u201d. In una societ\u00e0 dove il valore delle cose \u00e8 sempre suggerito da un cartellino del prezzo, fermarsi a soppesare la reale utilit\u00e0 degli oggetti, significa superare il concetto di \u201cmerce\u201d, dove le cose invece servono per quanti euro ci possono far guadagnare o spendere. Inoltre, \u00e8 divertente vedere quanto le persone a volte si trovino spiazzate da questa insolita domanda: in effetti, per quanto sia ovvia, nessuno ce la rivolge mai! Questo espediente ribalta la gerarchia di potere tra chi vende e chi compra, dando a quest&#8217;ultimo la completa facolt\u00e0 di decidere, ponendosi di fronte all&#8217;interrogativo etico se approfittarsi o meno di questo inaspettato vantaggio. E&#8217; una pratica che mette in gioco concetti come sincerit\u00e0, solidariet\u00e0 e complicit\u00e0 tra chi compra e chi vende: in fin dei conti, prendere qualcosa dalla nostra distro significa supportare le nostre attivit\u00e0, essere in qualche modo parte del nostro collettivo. In definitiva, \u00e8 un nuovo modo di intendere lo scambio di cose, valorizzando le idee e la sostanza, non pi\u00f9 il profitto e il tornaconto personale. Immagino che molti si chiederanno se la cosa possa funzionare e sia, per cos\u00ec dire, \u201csostenibile\u201d per chi la pratica. Beh, noi la pratichiamo da qualche anno ormai&#8230;Se funziona? Provate voi stessi!<\/p>\n<p align=\"JUSTIFY\"><b>6) Avete avuto modo di suonare anche all&#8217;estero, in Paesi come la Germania e la Grecia, due realt\u00e0 che in questo momento storico sono forse quasi due esempi antitetici nell&#8217;analisi della situazione socio-economica europea. Come avete percepito le rispettive comunit\u00e0 punk? E che risposta ha avuto la vostra musica? Quali sono le cose che vi sono piaciute e che vorreste importare in Italia?<\/b><\/p>\n<p align=\"JUSTIFY\">Germania e Grecia, ovvio, sono molto diverse, ma le scene di entrambi i paesi rappresentano realt\u00e0 molto belle per quanto riguarda il punk e il DIY. La Germania, per noi, rappresenta un sano equilibrio tra musica e attivismo, tra buona organizzazione, diciamo, \u00a0\u201ctecnica e logistica\u201d e un contesto nel quale si respira un interesse per tutto ci\u00f2 che sta dietro all\u2019etica DIY e ha a che fare con la politica. Un altro aspetto che amo della Germania: ai tedeschi interessa poco chi sei, come ti vesti, qual\u2019\u00e8 la tua provenienza o quanti amici hai su facebook: ai tedeschi interessa la sostanza, la musica, quello che fai e quello che dici. E\u2019 un fatto molto importante, che determina il fatto che non si creino tante divisioni tra generi e ambienti, come accade da noi.<\/p>\n<p align=\"JUSTIFY\">Certo, la Germania \u00e8 un paese relativamente ricco e con un welfare solido: questo potrebbe far pensare che l\u00ec sia tutto pi\u00f9 semplice; pu\u00f2 far sospettare che la musica e l\u2019attivismo politico se lo possano permettere in particolare quelle persone che vivono una certa stabilit\u00e0 di vita\u2026 in questo senso si inserisce il discorso sulla Grecia, che \u00e8 forse una delle realt\u00e0 pi\u00f9 vitali che abbiamo mai visto nel contesto punk DIY. L\u00ec la situazione economica la si conosce tutti, ed \u00e8 tangibile una volta che si mette piede da quelle parti. Fatto sta che la cosiddetta crisi non ha minimamente scalfito l\u2019entusiasmo e l\u2019attivismo della comunit\u00e0 punk greca. Anzi, forse lo ha addirittura rafforzato. Noi siamo stati a suonare in Grecia tre volte, la prima nel 2007, quindi precedentemente alla \u201ccrisi\u201d, e abbiamo visto crescere l\u2019entusiasmo in questi anni. Lo scorso marzo, nell\u2019attuale situazione socio-economica del paese, abbiamo suonato all\u2019universit\u00e0 occupata di Atene, davanti a pi\u00f9 di mille persone: situazioni e numeri impensabili per la nostra (e non solo) scena punk. Oltre alla passione e alla voglia di partecipare, trai greci c\u2019\u00e8 l\u2019idea che la politica sia un fatto che coinvolge tutti: tutti si sentono \u201cpoliticizzati\u201d, costretti a prendere una posizione sulla realt\u00e0 che li circonda. Questo forse \u00e8 un po\u2019 paragonabile a quello che succedeva anche in Italia negli anni \u201970: partecipazione, attivismo e politica erano aspetti del quotidiano.<\/p>\n<p align=\"JUSTIFY\">Per quanto riguarda la nostra musica, direi che fortunatamente ha sempre un buon riscontro all\u2019estero. Dal vivo facciamo i pezzi pi\u00f9 ballabili, perch\u00e9 pensiamo che la musica punk sia fatta anche per questo, oltre a far pensare, deve essere una festa da condividere con le persone che hai davanti, intorno. In paesi come Germania e Grecia, come gi\u00e0 detto, ci si fanno molte meno menate per quanto riguarda i generi musicali, la discendenza artistica di chi suona e gli aspetti estetici della questione. Questo \u00e8 fondamentale, e vorremmo che fosse cos\u00ec anche in Italia (dove, purtroppo, \u00e8 l\u2019esatto opposto!).<\/p>\n<p align=\"JUSTIFY\"><a href=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/557079_10151725916317717_1014388066_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2515 aligncenter\" alt=\"\" src=\"http:\/\/www.epidemicrecords.net\/2018\/wp-content\/uploads\/2014\/01\/557079_10151725916317717_1014388066_n1-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/557079_10151725916317717_1014388066_n1-300x200.jpg 300w, https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/557079_10151725916317717_1014388066_n1-768x512.jpg 768w, https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/557079_10151725916317717_1014388066_n1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\"><b>7) Sul vostro blog si legge un trafiletto, intitolato &#8220;Coerenza&#8221;. (sulla colonna di destra, <\/b><span style=\"color: #000080;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.facebook.com\/l.php?u=http%3A%2F%2Fwww.kalashnikov-collective.blogspot.it%2F&amp;h=9AQHirJdC&amp;s=1\" target=\"_blank\">http:\/\/www.kalashnikov-collective.blogspot.it\/<\/a><\/span><\/span><b>). Vi scontrate spesso con questo genere di critiche? Siete sempre cos\u00ec positivi oppure delle volte vi chiedete &#8220;ma chi ce l&#8217;ha fatto fare?&#8221;, se non &#8220;ma perch\u00e8 devono rompere le palle proprio a me?&#8221;<\/b><\/p>\n<p align=\"JUSTIFY\">Fortunatamente, nel giro punk accade molto di rado, fuori molto pi\u00f9 spesso. Il problema \u00e8 che le persone hanno paura delle scelte radicali, delle prese di posizione nette, delle scelte controcorrente, perch\u00e9 mettono in discussione quel sistema di ovviet\u00e0 che fanno andare avanti il mondo, permettendo loro di stare con il culo al caldo fregandosene dei problemi che stanno intorno. La massa tende al ribasso e sta bene nel suo brodo di mediocrit\u00e0. Se metti in discussioni le sicurezze delle persone, nella maggior parte dei casi riceverai diffidenza e, nei casi peggiori, disprezzo. Il disappunto di tanta gente nasce dal fatto che gli rovini la tranquillit\u00e0, gli ricordi che esiste una cosa che si chiama coscienza e che loro hanno seppellito tanto tempo fa\u2026 Per\u00f2 il problema non \u00e8 nostro, sta fuori, per cui non ce ne preoccupiamo troppo\u2026<\/p>\n<p align=\"JUSTIFY\"><b>8) Quanto \u00e8 importante la musica nella nuova societ\u00e0 che le varie correnti rivoluzionarie vogliono creare? E&#8217; una proporzione giusta oppure secondo voi l&#8217;arte viene considerata poco nella costruzione di un mondo migliore?<\/b><\/p>\n<p align=\"JUSTIFY\">La musica \u00e8 poesia, letteratura, immaginazione&#8230; E\u2019 una forma di comunicazione, un linguaggio molto potente. Per\u00f2 spetta ai musicisti utilizzarlo al meglio. E farlo funzionare! Ogni forma di espressione pu\u00f2 cadere nell\u2019insignificanza, nel mutismo, farsi sommergere dal frastuono di quello che sta intorno se diventa un gesto gratuito, narcisistico o dettato dalla noia. L\u2019arte dovrebbe emozionare o far pensare per poter \u201cfunzionare\u201d, per parlare ad un interlocutore; se non fa niente di tutto questo, purtroppo, scivola nell\u2019indifferenza e resta mero intrattenimento. Che non c\u2019\u00e8 niente di male in s\u00e9, a patto che non si abbiano troppe ambizioni\u2026 perch\u00e9 cos\u00ec ci si abitua a sottovalutare la forza e il ruolo sociale dell\u2019arte ed in particolare della musica: oggi ci si \u00e8 abituati a pensare alla musica come ad un oggetto di consumo, una forma di intrattenimento che non deve prendersi troppe responsabilit\u00e0, un gesto narcisistico, l\u2019accessorio di un determinato look\u2026<\/p>\n<p align=\"JUSTIFY\">Comunque la musica, come tutte le espressioni \u201cartistiche\u201d, non cambia il mondo (purtroppo), ma pu\u00f2 cambiare le persone alle quali spetta il compito di cambiare il mondo! E in particolare, pensiamo che l\u2019arte cambi prima di tutto le persone che la praticano, che la fanno. E per arte non intendiamo qualcosa che appartiene ad una \u00e9lite o qualcosa che necessita di particolari conoscenze o abilit\u00e0 per essere praticata, ma una cose per tutti. Una societ\u00e0 che invitasse le persone ad essere artisti e a praticare liberamente l\u2019arte sarebbe l\u2019anticamera di un mondo migliore&#8230;<\/p>\n<p align=\"JUSTIFY\"><b>9) Per concludere, una domanda terra-terra: cosa bolle in pentola per i Kalashnikov? Cosa vi piacerebbe fare?<\/b><\/p>\n<p align=\"JUSTIFY\">Semplicemente&#8230;.continuare a fare quello che gi\u00e0 facciamo! Ovvero: suonare viaggiando in giro per il mondo, registrare musica, portare avanti progetti nell&#8217;ambito degli spazi occupati, autogestendoci e intessendo relazioni di amicizia autentiche con chi pensa che, nel mondo, le cose non vadano esattamente per il verso giusto. Cosa ci pu\u00f2 essere di meglio?<\/p>\n<p>&nbsp;<\/p>\n<p>Info:<\/p>\n<div><a href=\"http:\/\/www.kalashni.net\/\" target=\"_blank\" rel=\"nofollow nofollow\">www.kalashni.net<\/a><br \/>\n<a href=\"http:\/\/www.romanticpunx.blogspot.com\/\" target=\"_blank\" rel=\"nofollow nofollow\">www.romanticpunx.blogspot.com<\/a><br \/>\n<a href=\"http:\/\/www.kalashnikov-collective.blogspot.com\/\" target=\"_blank\" rel=\"nofollow nofollow\">www.kalashnikov-collective.blogspot.com<\/a><\/div>\n<div><a href=\"https:\/\/www.facebook.com\/pages\/Kalashnikov-Collective\/76292207716?id=76292207716\" target=\"_blank\">https:\/\/www.facebook.com\/pages\/Kalashnikov-Collective\/76292207716?id=76292207716<\/a><\/div>\n<p><cite>\u00a0<\/cite><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Kalashnikov (o meglio, Kalashnikov Collective) sono pi\u00f9 che una band e negli anni l&#8217;hanno saputo dimostrare al meglio. Una realt\u00e0 creativa, vivace e al di fuori di molti schemi. Intervistarli \u00e8 stato un piacere: leggere risposte cos\u00ec sincere e che hanno il sapore di una coscienza conquistata e forgiata negli anni mi ha fatto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records\" \/>\n<meta property=\"og:description\" content=\"I Kalashnikov (o meglio, Kalashnikov Collective) sono pi\u00f9 che una band e negli anni l&#8217;hanno saputo dimostrare al meglio. Una realt\u00e0 creativa, vivace e al di fuori di molti schemi. Intervistarli \u00e8 stato un piacere: leggere risposte cos\u00ec sincere e che hanno il sapore di una coscienza conquistata e forgiata negli anni mi ha fatto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/\" \/>\n<meta property=\"og:site_name\" content=\"Epidemic Records\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/epidemicrecordshc\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-09T10:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@epidemicrecs\" \/>\n<meta name=\"twitter:site\" content=\"@epidemicrecs\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/\"},\"author\":{\"name\":\"Gabriele\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#\\\/schema\\\/person\\\/e2cff227657e3cabdde72daaf4b738b2\"},\"headline\":\"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band &#8211; intervista &#8211; [italian only]\",\"datePublished\":\"2014-01-09T10:43:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/\"},\"wordCount\":3733,\"publisher\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/12356_10151687915192717_1110361568_n1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/\",\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/\",\"name\":\"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/12356_10151687915192717_1110361568_n1.jpg\",\"datePublished\":\"2014-01-09T10:43:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/12356_10151687915192717_1110361568_n1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/12356_10151687915192717_1110361568_n1.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/2014\\\/01\\\/09\\\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/en\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band &#8211; intervista &#8211; [italian only]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#website\",\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/\",\"name\":\"Epidemic Records\",\"description\":\"This Is More Than Music. This Is What We Believe In.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#organization\",\"name\":\"Epidemic Records\",\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-wp.png\",\"contentUrl\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-wp.png\",\"width\":200,\"height\":196,\"caption\":\"Epidemic Records\"},\"image\":{\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/epidemicrecordshc\",\"https:\\\/\\\/x.com\\\/epidemicrecs\",\"http:\\\/\\\/www.instagram.com\\\/epidemicrecordshc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/#\\\/schema\\\/person\\\/e2cff227657e3cabdde72daaf4b738b2\",\"name\":\"Gabriele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g\",\"caption\":\"Gabriele\"},\"url\":\"https:\\\/\\\/www.epidemicrecords.net\\\/v2019\\\/author\\\/gabriele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/","og_locale":"it_IT","og_type":"article","og_title":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records","og_description":"I Kalashnikov (o meglio, Kalashnikov Collective) sono pi\u00f9 che una band e negli anni l&#8217;hanno saputo dimostrare al meglio. Una realt\u00e0 creativa, vivace e al di fuori di molti schemi. Intervistarli \u00e8 stato un piacere: leggere risposte cos\u00ec sincere e che hanno il sapore di una coscienza conquistata e forgiata negli anni mi ha fatto [&hellip;]","og_url":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/","og_site_name":"Epidemic Records","article_publisher":"http:\/\/www.facebook.com\/epidemicrecordshc","article_published_time":"2014-01-09T10:43:46+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg","type":"image\/jpeg"}],"author":"Gabriele","twitter_card":"summary_large_image","twitter_creator":"@epidemicrecs","twitter_site":"@epidemicrecs","twitter_misc":{"Scritto da":"Gabriele","Tempo di lettura stimato":"19 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#article","isPartOf":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/"},"author":{"name":"Gabriele","@id":"https:\/\/www.epidemicrecords.net\/v2019\/#\/schema\/person\/e2cff227657e3cabdde72daaf4b738b2"},"headline":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band &#8211; intervista &#8211; [italian only]","datePublished":"2014-01-09T10:43:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/"},"wordCount":3733,"publisher":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/#organization"},"image":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#primaryimage"},"thumbnailUrl":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg","articleSection":["Blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/","url":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/","name":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band - intervista - [italian only] - Epidemic Records","isPartOf":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#primaryimage"},"image":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#primaryimage"},"thumbnailUrl":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg","datePublished":"2014-01-09T10:43:46+00:00","breadcrumb":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#primaryimage","url":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg","contentUrl":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2014\/01\/12356_10151687915192717_1110361568_n1.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.epidemicrecords.net\/v2019\/2014\/01\/09\/kalashnikov-collective-piu-che-una-band-intervista-italian-only\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.epidemicrecords.net\/v2019\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"KALASHNIKOV COLLECTIVE: pi\u00f9 che una band &#8211; intervista &#8211; [italian only]"}]},{"@type":"WebSite","@id":"https:\/\/www.epidemicrecords.net\/v2019\/#website","url":"https:\/\/www.epidemicrecords.net\/v2019\/","name":"Epidemic Records","description":"This Is More Than Music. This Is What We Believe In.","publisher":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.epidemicrecords.net\/v2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.epidemicrecords.net\/v2019\/#organization","name":"Epidemic Records","url":"https:\/\/www.epidemicrecords.net\/v2019\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.epidemicrecords.net\/v2019\/#\/schema\/logo\/image\/","url":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2019\/05\/logo-wp.png","contentUrl":"https:\/\/www.epidemicrecords.net\/v2019\/wp-content\/uploads\/2019\/05\/logo-wp.png","width":200,"height":196,"caption":"Epidemic Records"},"image":{"@id":"https:\/\/www.epidemicrecords.net\/v2019\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/epidemicrecordshc","https:\/\/x.com\/epidemicrecs","http:\/\/www.instagram.com\/epidemicrecordshc"]},{"@type":"Person","@id":"https:\/\/www.epidemicrecords.net\/v2019\/#\/schema\/person\/e2cff227657e3cabdde72daaf4b738b2","name":"Gabriele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5fcb4f27d198f6c2162bc92e4726ffd79ebd15d254ed5679485ba47495e6466?s=96&d=mm&r=g","caption":"Gabriele"},"url":"https:\/\/www.epidemicrecords.net\/v2019\/author\/gabriele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/posts\/2509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/comments?post=2509"}],"version-history":[{"count":0,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/posts\/2509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/media?parent=2509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/categories?post=2509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epidemicrecords.net\/v2019\/wp-json\/wp\/v2\/tags?post=2509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}